{"id":684,"date":"2022-03-15T14:46:19","date_gmt":"2022-03-15T13:46:19","guid":{"rendered":"https:\/\/www.fiesta-eventfactory-mallorca.com\/contacte-con\/"},"modified":"2024-03-31T16:11:51","modified_gmt":"2024-03-31T14:11:51","slug":"contacte-con","status":"publish","type":"page","link":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/contacte-con\/","title":{"rendered":"Contacte con"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"684\" class=\"elementor elementor-684 elementor-41\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05ec5c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05ec5c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f64c684\" data-id=\"f64c684\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c850e86 elementor-widget elementor-widget-heading\" data-id=\"c850e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Contacto - Solicitud<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2dc92cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dc92cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-001784c\" data-id=\"001784c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaaa0cd uael-gf-check-yes uael-gf-ajax-true uael-gf-style-box uael-gf-input-size-sm uael-gf-enable-classes-no uael-gf-check-default-no uael-gf-button-left uael-gf-btn-size-sm elementor-widget elementor-widget-uael-gf-styler\" data-id=\"aaaa0cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-gf-styler.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gf-style uael-gf-check-style elementor-clickable\">\n\t<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_1' >\n                        <div class='gform_heading'>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>&quot;<span class=\"gfield_required gfield_required_asterisk\">*<\/span>&quot; se\u00f1ala los campos obligatorios<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_1'  action='\/es\/wp-json\/wp\/v2\/pages\/684' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_1_9\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_9'><span class='gform-field-label__text'>Facebook<\/span><\/label><div class='ginput_container'><input name='input_9' id='input_1_9' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_1_9'>Este campo es un campo de validaci\u00f3n y debe quedar sin cambios.<\/div><\/div><fieldset id=\"field_1_1\" class=\"gfield gfield--type-name gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Nombre<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_1_1'>\n                            \n                            <span id='input_1_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.3' id='input_1_1_3' value='' tabindex='2'  aria-required='true'     \/>\n                                                    <label for='input_1_1_3' class='gform-field-label gform-field-label--type-sub '>Nombre<\/label>\n                                                <\/span>\n                            \n                            <span id='input_1_1_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.6' id='input_1_1_6' value='' tabindex='4'  aria-required='true'     \/>\n                                                    <label for='input_1_1_6' class='gform-field-label gform-field-label--type-sub '>Apellidos<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><fieldset id=\"field_1_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>E-Mail<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container_email gform-grid-row' id='input_1_2_container'>\n                                <span id='input_1_2_1_container' class='ginput_left gform-grid-col gform-grid-col--size-auto'>\n                                    <input class='' type='email' name='input_2' id='input_1_2' value='' tabindex='6'   aria-required=\"true\" aria-invalid=\"false\"  \/>\n                                    <label for='input_1_2' class='gform-field-label gform-field-label--type-sub '>Introduce un email<\/label>\n                                <\/span>\n                                <span id='input_1_2_2_container' class='ginput_right gform-grid-col gform-grid-col--size-auto'>\n                                    <input class='' type='email' name='input_2_2' id='input_1_2_2' value='' tabindex='7'   aria-required=\"true\" aria-invalid=\"false\"  \/>\n                                    <label for='input_1_2_2' class='gform-field-label gform-field-label--type-sub '>Confirmar email<\/label>\n                                <\/span>\n                                <div class='gf_clear gf_clear_complex'><\/div>\n                            <\/div><\/fieldset><div id=\"field_1_3\" class=\"gfield gfield--type-phone gfield--phone-format-international gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_3'><span class='gform-field-label__text'>Tel\u00e9fono<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_3' id='input_1_3' type='tel' value='' class='medium' tabindex='8'  aria-required=\"true\" aria-invalid=\"false\"    \/><\/div><\/div><div id=\"field_1_4\" class=\"gfield gfield--type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_4'><span class='gform-field-label__text'>N\u00famero de personas<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_1_4' type='text' value='' class='small'   tabindex='9'  aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_1_5\" class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-default-icon gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_5'><span class='gform-field-label__text'>Fecha<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_date'>\n\t\t\t\t\t<input\n\t\t\t\t\tplaceholder='dd.mm.aaaa'\n\t\t\t\t\tid='input_1_5'\n\t\t\t\t\tclass='datepicker gform-datepicker dmy_dot datepicker_with_icon gdatepicker_with_icon'\n\t\t\t\t\ttype='text'\n\t\t\t\t\tname='input_5'\n\t\t\t\t\tvalue=''\n\t\t\t\t\t \n\t\t\t\t\taria-invalid=\"false\" \n\t\t\t\t\taria-required=\"true\"\n\t\t\t\t\ttabindex='10' \n\t\t\t\t\t\n\t\t\t\t\tdata-mask=\"99.99.9999\"\n\t\t\t\t\t\/>\n\t\t\t\t<kbd id='keyboardHint_input_1_5' hidden class='down'><\/kbd>\n\t\t\t\t<button type='button' id='datepicker_toggle_input_1_5' class='gform-datepicker-toggle gform-datepicker-toggle--default accCalendar aria-date-picker gform-button gform-theme-button gform-theme-button--simple gform-theme-button--simple-in-ctrl' aria-expanded='false' aria-controls='input_1_5' aria-label='Fecha: Choose date on calendar' >\n\t\t\t\t\t\t\t<span class=\"gform-calendar-icon gform-datepicker-toggle-icon gform-datepicker-toggle-icon--default dashicons dashicons-calendar-alt\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t<\/button>\n\t\t\t<\/div><\/div><div id=\"field_1_6\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_6'><span class='gform-field-label__text'>mensaje<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_6' id='input_1_6' class='textarea medium' tabindex='11'    aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><fieldset id=\"field_1_8\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield_contains_required field_sublabel_below gfield--has-description field_description_above field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Consentimiento<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='gfield_description gfield_consent_description' id='gfield_consent_description_1_8'><div class='gfield_consent_description_text' tabindex='0'>Doy mi consentimiento para que mis datos se almacenen de forma permanente con el fin de ponerse en contacto conmigo y asignarlos para posibles consultas. Nota: Puede revocar este consentimiento en cualquier momento con efectos para el futuro enviando un correo electr\u00f3nico a info@fiestapartyservice.com.<\/div><\/div><div class='ginput_container ginput_container_consent'><input name='input_8.1' id='input_1_8_1' type='checkbox' value='1' tabindex='12' aria-describedby=\"gfield_consent_description_1_8\" aria-required=\"true\" aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_1_8_1' ><span class='gform-field-label__text'>Acepto la pol\u00edtica de privacidad.<\/span><\/label><input type='hidden' name='input_8.2' value='Acepto la pol\u00edtica de privacidad.' class='gform_hidden' \/><input type='hidden' name='input_8.3' value='1' class='gform_hidden' \/><\/div><\/fieldset><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <button type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' tabindex='13'>Enviar<\/button> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='bDgo9e5nrTNQxDa0\/HsKrPg3nLrhMikl6L6v0Psl8A8lpLDIcxfDGj1JzSKMc0ff4AiYXyrih67AOaKy2QZ7ebjAyWwNg\/4QssiXKmVkA88CJL4=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJ7XCI4LjFcIjpcIjY3YmE1ODAzOThlMWMxYTAxYTlhYzQ0YjBmNzlmMzQ0XCIsXCI4LjJcIjpcIjBiOWQ5MzY1NWNlMTgwMjA2N2Y0ZjU4ODNiMDY5NmU1XCIsXCI4LjNcIjpcIjY3YmE1ODAzOThlMWMxYTAxYTlhYzQ0YjBmNzlmMzQ0XCIsXCJnZm9ybV9zdWJtaXNzaW9uX21ldGhvZFwiOltcImU3YzhhM2FhZDYwYmY5MWUyMGU0N2FhMzFjYmFhMGE1XCIsXCJmZjAxMWI5MjI5MzUzZTVlNjAwZmJkMWU3YjhiYThjNVwiXSxcImdmb3JtX3RoZW1lXCI6XCJjNWZlY2UwZDgyOWE2ZGRmYzg3MzRlNGQ4YWExMGU5NFwiLFwiZ2Zvcm1fc3R5bGVfc2V0dGluZ3NcIjpcIjM3YTZiMTMxOWRkNmFlYmY3YTMzMmI4YzZiYmZiNjNkXCIsXCJmb3JtX2lkXCI6XCI2N2JhNTgwMzk4ZTFjMWEwMWE5YWM0NGIwZjc5ZjM0NFwiLFwidXJsXCI6XCJiNGIzNzk0MWZlMDJiMWFlNTVlZjhhMzNhZTRiOTY3MlwiLFwic3RhdGVfdGltZXN0YW1wXCI6XCI0OWIzZDU1YWYxMTU2NTU4NDkzZjI3MDY0MmYzNGQ3MFwifSIsIjE5NWMwYjFjMjhmM2I2YmY0ZTZhNDJhOTE4ZDRkOWQxIiwxNzg4MzA4NTYyXQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contacto &#8211; Solicitud \u201e*\u201c zeigt erforderliche Felder an Nombre* Vorname Nachname E-Mail* E-Mail eingeben E-Mail best\u00e4tigen Tel\u00e9fono*N\u00famero de personas* Fecha* TT Punkt MM Punkt JJJJ mensaje* Consentimiento* Doy mi consentimiento para que mis datos se almacenen de forma permanente con el fin de ponerse en contacto conmigo y asignarlos para posibles consultas. Nota: Puede revocar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-684","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/wp-json\/wp\/v2\/pages\/684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/wp-json\/wp\/v2\/comments?post=684"}],"version-history":[{"count":3,"href":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/wp-json\/wp\/v2\/pages\/684\/revisions"}],"predecessor-version":[{"id":1088,"href":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/wp-json\/wp\/v2\/pages\/684\/revisions\/1088"}],"wp:attachment":[{"href":"https:\/\/www.fiesta-eventfactory-mallorca.com\/es\/wp-json\/wp\/v2\/media?parent=684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}